{"id":6,"count":1,"description":"","link":"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/","name":"Color Theory","slug":"color-theory","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Color Theory Archives - Oigny Lite<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Color Theory Archives - Oigny Lite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/\" \/>\n<meta property=\"og:site_name\" content=\"Oigny Lite\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gutenverse.com\/oigny-lite\/wp-content\/uploads\/sites\/29\/2026\/04\/ss-oigny-lite-home.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1944\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/\",\"url\":\"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/\",\"name\":\"Color Theory Archives - Oigny Lite\",\"isPartOf\":{\"@id\":\"https:\/\/gutenverse.com\/oigny-lite\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gutenverse.com\/oigny-lite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Color Theory\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gutenverse.com\/oigny-lite\/#website\",\"url\":\"https:\/\/gutenverse.com\/oigny-lite\/\",\"name\":\"Oigny Lite\",\"description\":\"Free Creative Digital Agency WordPress Block Theme\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gutenverse.com\/oigny-lite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Color Theory Archives - Oigny Lite","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/","og_locale":"en_US","og_type":"article","og_title":"Color Theory Archives - Oigny Lite","og_url":"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/","og_site_name":"Oigny Lite","og_image":[{"width":1440,"height":1944,"url":"https:\/\/gutenverse.com\/oigny-lite\/wp-content\/uploads\/sites\/29\/2026\/04\/ss-oigny-lite-home.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/","url":"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/","name":"Color Theory Archives - Oigny Lite","isPartOf":{"@id":"https:\/\/gutenverse.com\/oigny-lite\/#website"},"breadcrumb":{"@id":"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/gutenverse.com\/oigny-lite\/category\/color-theory\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gutenverse.com\/oigny-lite\/"},{"@type":"ListItem","position":2,"name":"Color Theory"}]},{"@type":"WebSite","@id":"https:\/\/gutenverse.com\/oigny-lite\/#website","url":"https:\/\/gutenverse.com\/oigny-lite\/","name":"Oigny Lite","description":"Free Creative Digital Agency WordPress Block Theme","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gutenverse.com\/oigny-lite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/gutenverse.com\/oigny-lite\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gutenverse.com\/oigny-lite\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/gutenverse.com\/oigny-lite\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/gutenverse.com\/oigny-lite\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}